{"id":12839,"date":"2023-06-09T09:35:00","date_gmt":"2023-06-09T08:35:00","guid":{"rendered":"https:\/\/firmalex.com\/?p=12839"},"modified":"2023-07-10T09:37:27","modified_gmt":"2023-07-10T08:37:27","slug":"kapitalertragsteuer-in-spanien","status":"publish","type":"post","link":"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/","title":{"rendered":"Kapitalertragsteuer in Spanien"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote\"><p>Zu den Steuern f\u00fcr Gebietsfremde geh\u00f6rt die Kapitalertragssteuer. Diese Steuer ist insbesondere im Zusammenhang mit dem Kauf und Verkauf von Immobilien auf spanischem Territorium von gro\u00dfer Bedeutung.<\/p><\/blockquote>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 ez-toc-wrap-center counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\"><\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/#Was_ist_Kapitalertragssteuer\" >Was ist Kapitalertragssteuer?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/#Kapitalertragssteuer_fuer_Einwohner_in_Spanien\" >Kapitalertragssteuer f\u00fcr Einwohner in Spanien<\/a><ul class='ez-toc-list-level-5' ><li class='ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/#Verguenstigungen\" >Verg\u00fcnstigungen<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/#Kapitalertragssteuer_fuer_Gebietsfremde\" >Kapitalertragssteuer f\u00fcr Gebietsfremde<\/a><ul class='ez-toc-list-level-5' ><li class='ez-toc-heading-level-5'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/#Boni_und_Ermaessigungen\" >Boni und Erm\u00e4\u00dfigungen<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/#Weitere_Informationen\" >Weitere Informationen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/#Klaeren_Sie_Ihre_Zweifel\" >Kl\u00e4ren Sie Ihre Zweifel<\/a><\/li><\/ul><\/nav><\/div>\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Was_ist_Kapitalertragssteuer\"><\/span>Was ist Kapitalertragssteuer?<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>Die Kapitalertragssteuer <strong>ist eine Steuer, die gezahlt werden muss, wenn Gewinne aus dem Verkauf eines Verm\u00f6genswerts erzielt werden,<\/strong> beispielsweise einer Immobilie oder einer Investition auf spanischem Territorium. Wenn also der Wert des Verkaufs dieser Ware h\u00f6her ist als der Kaufpreis derselben, muss diese Steuer f\u00fcr die Differenz, also den Gewinn, gezahlt werden.<\/p>\n\n\n\n<p>Diese Steuer ist eine der wichtigsten beim Verkauf eines Hauses in Spanien.<\/p>\n\n\n\n<p>Obwohl diese Steuer in anderen L\u00e4ndern unabh\u00e4ngig funktioniert, <strong>ist sie in Spanien in der Einkommensteuer <\/strong>(IRPF) enthalten. Dar\u00fcber hinaus haben wir einige Unterschiede zwischen der Anwendung der Kapitalertragssteuer f\u00fcr Gebietsfremde und Gebietsans\u00e4ssige in Spanien festgestellt.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Kapitalertragssteuer_fuer_Einwohner_in_Spanien\"><\/span>Kapitalertragssteuer f\u00fcr Einwohner in Spanien<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>Damit eine Person als in Spanien steuerlich ans\u00e4ssig gilt, <strong>muss sie mindestens 183 Tage,<\/strong> also etwa sechs Monate, im Land bleiben.<\/p>\n\n\n\n<p>Auf Personen, die diese Voraussetzung erf\u00fcllen, wird die Steuer wie folgt erhoben:<\/p>\n\n\n\n<ul><li><strong>19 % <\/strong>f\u00fcr die ersten 6.000 Euro Gewinn.<\/li><li><strong>21 %,<\/strong> wenn die Leistung zwischen 6.000 und 50.000 Euro liegt.<\/li><li><strong>23 % <\/strong>ab 50.000 Euro bis 200.000 Euro.<\/li><li><strong>26% <\/strong>dar\u00fcber.<\/li><\/ul>\n\n\n\n<p>Der entsprechende Prozentsatz <strong>wird auf die Differenz zwischen dem Kaufpreis und dem Verkaufspreis <\/strong>des Verm\u00f6genswerts angewendet.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Verguenstigungen\"><\/span>Verg\u00fcnstigungen<span class=\"ez-toc-section-end\"><\/span><\/h5>\n\n\n\n<p>Obwohl der Steuersatz dieser Steuer hoch ist, gibt es einige Verg\u00fcnstigungen, die es Ihnen erm\u00f6glichen, die Steuer nicht zu zahlen oder erheblich zu senken.<\/p>\n\n\n\n<p><strong>Ausnahmeregelung f\u00fcr gew\u00f6hnlichen Aufenthalt<\/strong><\/p>\n\n\n\n<p>Wenn die aus dem Verkauf eines Verm\u00f6genswerts erzielten Gewinne in den Kauf eines Hauses investiert werden sollen, das als gew\u00f6hnlicher Wohnsitz dient, ist die <strong>Zahlung der Kapitalertragssteuer nicht erforderlich.<\/strong> Es gilt die sogenannte Ausnahmeregelung f\u00fcr den gew\u00f6hnlichen Aufenthalt.<\/p>\n\n\n\n<p>Daher m\u00fcssen zwei grundlegende Voraussetzungen erf\u00fcllt sein: <strong>dass die zu verkaufende Immobilie der gew\u00f6hnliche Aufenthaltsort ist und dass der Gewinn in den neuen gew\u00f6hnlichen Aufenthaltsort investiert wird.<\/strong> Au\u00dferdem ist es erforderlich, dass sich die Immobilie innerhalb der Europ\u00e4ischen Union befindet.<\/p>\n\n\n\n<p><strong>Verkauf einer Immobilie f\u00fcr Personen \u00fcber 65 Jahre<\/strong><\/p>\n\n\n\n<p>Wenn eine Person, die 65 Jahre oder \u00e4lter ist, eine Immobilie verkauft, <strong>muss sie diese Steuer nicht zahlen,<\/strong> unabh\u00e4ngig davon, wo die Gewinne investiert werden. Daher ist es ratsam, mit dem Verkauf bis zum Erreichen dieses Alters zu warten, wenn dieses bald erreicht ist.<\/p>\n\n\n\n<p>Die einzige Voraussetzung, die erf\u00fcllt sein muss, um von der Steuerbefreiung f\u00fcr Personen \u00fcber 65 Jahre zu profitieren, ist, dass <strong>die zu verkaufende Immobilie ihr gew\u00f6hnlicher Aufenthaltsort ist und dass sie seit mindestens drei Jahren bewohnt wurde.<\/strong><\/p>\n\n\n\n<p><strong>Reduzierung der Wertpapierk\u00e4ufe vor 1995<\/strong><\/p>\n\n\n\n<p>F\u00fcr Verk\u00e4ufe von Verm\u00f6genswerten, die vor 1995 erworben wurden, gibt es eine erhebliche Steuererm\u00e4\u00dfigung. Daher kann es auf Verm\u00f6genswerte angewendet werden, die <strong>bis Dezember 1994 erworben wurden. <\/strong>Hierzu ist Folgendes <strong>zu ber\u00fccksichtigen:<\/strong><\/p>\n\n\n\n<ul><li>Der Bonus wird auf <strong>die bis Januar 2006 erzielten Ertr\u00e4ge angerechnet.<\/strong> Nachfolgende Erh\u00f6hungen werden zum Normalsatz besteuert.<\/li><li>F\u00fcr die F\u00f6rderung musste die Immobilie oder Anlage einen <strong>Anschaffungswert von weniger als 400.000 Euro haben.<\/strong><\/li><\/ul>\n\n\n\n<p>Bei Vorliegen der Voraussetzungen setzen sich die K\u00fcrzungen zu <strong>11 % in Immobilien, 25 % in Aktien und 14 % in sonstigen Verm\u00f6genswerten zusammen.<\/strong><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Kapitalertragssteuer_fuer_Gebietsfremde\"><\/span>Kapitalertragssteuer f\u00fcr Gebietsfremde<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>F\u00fcr Personen, die sich weniger als 183 Tage auf spanischem Territorium aufhalten und daher als Nichtans\u00e4ssige gelten, ist diese Steuer etwas anders:<\/p>\n\n\n\n<ul><li><strong>Wer seinen gew\u00f6hnlichen Wohnsitz in einem Land der Europ\u00e4ischen Union,<\/strong> Norwegen oder Island hat, muss einen Steuersatz von <strong>19 % zahlen.<\/strong><\/li><li>Bei <strong>Wohnsitz au\u00dferhalb <\/strong>der Europ\u00e4ischen Union und der genannten L\u00e4nder betr\u00e4gt der Pauschalsatz auch <strong>19 %.<\/strong><\/li><\/ul>\n\n\n\n<h5 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Boni_und_Ermaessigungen\"><\/span>Boni und Erm\u00e4\u00dfigungen<span class=\"ez-toc-section-end\"><\/span><\/h5>\n\n\n\n<p>Nichtans\u00e4ssige in Spanien <strong>k\u00f6nnen den Bonus f\u00fcr den gew\u00f6hnlichen Aufenthalt <\/strong>in der Kapitalertragssteuer auf \u00e4hnliche Weise anwenden wie Gebietsans\u00e4ssige, sofern sie ihren Wohnsitz in einem Land der Europ\u00e4ischen Union haben, das ein Steuerabkommen mit Spanien hat.<\/p>\n\n\n\n<p>Die Kapitalertragssteuer ist eine Steuer f\u00fcr Gebietsfremde und Gebietsans\u00e4ssige, die dann erhoben wird, wenn aus dem Verkauf eines Verm\u00f6genswerts Vorteile erzielt werden, d. h. wenn der Verkaufswert den Kaufwert \u00fcbersteigt. Einwohner zahlen je nach erhaltener Leistung zwischen 19 % und 26 % und k\u00f6nnen teilweise auf die bestehenden Zuschl\u00e4ge zur\u00fcckgreifen. F\u00fcr Nichtans\u00e4ssige betr\u00e4gt der Satz 19 %.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Weitere_Informationen\"><\/span>Weitere Informationen<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>Dieser Artikel ist Teil unseres Service f\u00fcr den <a href=\"https:\/\/firmalex.com\/de\/steuern-spanien-nichtresidenten-auslander-denia-javea-calpe-altea-benissa-benidorm-alicante-valencia-costa-blanca\/\" target=\"_blank\" rel=\"noreferrer noopener\">Steuern in Spanien<\/a>. In diesem Bereich finden Sie alle n\u00fctzlichen Informationen zu diesem Thema, einschlie\u00dflich eines vollst\u00e4ndigen Leitfadens zum Thema <a href=\"https:\/\/firmalex.com\/de\/steuern-in-spanien-fur-nicht-residenten-und-auslander\/\" target=\"_blank\" rel=\"noreferrer noopener\">Steuern in Spanien f\u00fcr Nicht-Residenten und Ausl\u00e4nder<\/a>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Klaeren_Sie_Ihre_Zweifel\"><\/span>Kl\u00e4ren Sie Ihre Zweifel<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>&#x2705; Unsere Mitarbeiter sprechen flie\u00dfend Spanisch, Valencianisch, Englisch und Deutsch, so dass Sie mit uns in Ihrer eigenen Sprache kommunizieren k\u00f6nnen und so Ihre Fragen klar l\u00f6sen k\u00f6nnen.<\/p>\n\n\n\n<p>&#x1f4cd; Denia \u2013 Plaza del Convento, 6 \u2013 Zwischengeschoss pta. B<br>&#x1f4cd; Valencia \u2013 Calle Creu Roja, 1 \u2013 Block 6, Etage 1, T\u00fcr 10 (*nur mit vorheriger Zitierung)<\/p>\n\n\n\n<p>&#x2709;&#x1f4de;Kontakt: <a href=\"mailto:info@firmalex.com\" target=\"_blank\" rel=\"noreferrer noopener\">info@firmalex.com<\/a> \u2013 Tel. <a href=\"tel:+34966421416\" target=\"_blank\" rel=\"noreferrer noopener\">+34 966 421 416<\/a> \u2013 Whatsapp <a href=\"https:\/\/wa.me\/34622497615\" target=\"_blank\" rel=\"noreferrer noopener\">+34 622 497 615<\/a><\/p>\n\n\n\n<p>Folgen Sie uns: <a href=\"https:\/\/www.facebook.com\/FIRMALEXcom\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a> &#8211; <a href=\"https:\/\/www.linkedin.com\/company\/firmalexcom\/\" target=\"_blank\" rel=\"noreferrer noopener\">LinkedIn<\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zu den Steuern f\u00fcr Gebietsfremde geh\u00f6rt die Kapitalertragssteuer. Diese Steuer ist insbesondere im Zusammenhang mit dem Kauf und Verkauf von Immobilien auf spanischem Territorium von gro\u00dfer Bedeutung. Was ist Kapitalertragssteuer? Die Kapitalertragssteuer ist eine Steuer, die gezahlt werden muss, wenn Gewinne aus dem Verkauf eines Verm\u00f6genswerts erzielt werden, beispielsweise einer Immobilie oder einer Investition auf [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12840,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[247,212,239,243,235],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kapitalertragsteuer in Spanien - FIRMALEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kapitalertragsteuer in Spanien - FIRMALEX\" \/>\n<meta property=\"og:description\" content=\"Zu den Steuern f\u00fcr Gebietsfremde geh\u00f6rt die Kapitalertragssteuer. Diese Steuer ist insbesondere im Zusammenhang mit dem Kauf und Verkauf von Immobilien auf spanischem Territorium von gro\u00dfer Bedeutung. Was ist Kapitalertragssteuer? Die Kapitalertragssteuer ist eine Steuer, die gezahlt werden muss, wenn Gewinne aus dem Verkauf eines Verm\u00f6genswerts erzielt werden, beispielsweise einer Immobilie oder einer Investition auf [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/\" \/>\n<meta property=\"og:site_name\" content=\"FIRMALEX\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-09T08:35:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-10T08:37:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/firmalex.com\/wp-content\/uploads\/2023\/07\/kapitalertragsteuer-in-spanien.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Firmalex\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Firmalex\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/\"},\"author\":{\"name\":\"Firmalex\",\"@id\":\"https:\/\/firmalex.com\/#\/schema\/person\/910549a246ed3ba83a193ed7ecbb51d2\"},\"headline\":\"Kapitalertragsteuer in Spanien\",\"datePublished\":\"2023-06-09T08:35:00+00:00\",\"dateModified\":\"2023-07-10T08:37:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/\"},\"wordCount\":821,\"publisher\":{\"@id\":\"https:\/\/firmalex.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/firmalex.com\/wp-content\/uploads\/2023\/07\/kapitalertragsteuer-in-spanien.jpg\",\"articleSection\":[\"Kauf und Verkauf von Immobilien\",\"Neueste Artikel\",\"Steuerberatung\",\"Steuern in Spanien\",\"Unternehmensberatung\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/\",\"url\":\"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/\",\"name\":\"Kapitalertragsteuer in Spanien - FIRMALEX\",\"isPartOf\":{\"@id\":\"https:\/\/firmalex.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/firmalex.com\/wp-content\/uploads\/2023\/07\/kapitalertragsteuer-in-spanien.jpg\",\"datePublished\":\"2023-06-09T08:35:00+00:00\",\"dateModified\":\"2023-07-10T08:37:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/#primaryimage\",\"url\":\"https:\/\/firmalex.com\/wp-content\/uploads\/2023\/07\/kapitalertragsteuer-in-spanien.jpg\",\"contentUrl\":\"https:\/\/firmalex.com\/wp-content\/uploads\/2023\/07\/kapitalertragsteuer-in-spanien.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/firmalex.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kapitalertragsteuer in Spanien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/firmalex.com\/#website\",\"url\":\"https:\/\/firmalex.com\/\",\"name\":\"FIRMALEX\",\"description\":\"Rechts-, Steuer-, Arbeits-, Buchhaltungs- und Unternehmensberatung in Denia (Alicante) und Valencia [Spanien]. Anwalt und Steuerberater.\",\"publisher\":{\"@id\":\"https:\/\/firmalex.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/firmalex.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/firmalex.com\/#organization\",\"name\":\"Firmalex\",\"url\":\"https:\/\/firmalex.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/firmalex.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/firmalex.com\/wp-content\/uploads\/2015\/02\/logo.jpg\",\"contentUrl\":\"https:\/\/firmalex.com\/wp-content\/uploads\/2015\/02\/logo.jpg\",\"width\":371,\"height\":161,\"caption\":\"Firmalex\"},\"image\":{\"@id\":\"https:\/\/firmalex.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/firmalex.com\/#\/schema\/person\/910549a246ed3ba83a193ed7ecbb51d2\",\"name\":\"Firmalex\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/firmalex.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f6db6b06d3c80b6856de62666826e8b?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f6db6b06d3c80b6856de62666826e8b?s=96&d=blank&r=g\",\"caption\":\"Firmalex\"},\"sameAs\":[\"https:\/\/firmalex.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kapitalertragsteuer in Spanien - FIRMALEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/","og_locale":"de_DE","og_type":"article","og_title":"Kapitalertragsteuer in Spanien - FIRMALEX","og_description":"Zu den Steuern f\u00fcr Gebietsfremde geh\u00f6rt die Kapitalertragssteuer. Diese Steuer ist insbesondere im Zusammenhang mit dem Kauf und Verkauf von Immobilien auf spanischem Territorium von gro\u00dfer Bedeutung. Was ist Kapitalertragssteuer? Die Kapitalertragssteuer ist eine Steuer, die gezahlt werden muss, wenn Gewinne aus dem Verkauf eines Verm\u00f6genswerts erzielt werden, beispielsweise einer Immobilie oder einer Investition auf [&hellip;]","og_url":"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/","og_site_name":"FIRMALEX","article_published_time":"2023-06-09T08:35:00+00:00","article_modified_time":"2023-07-10T08:37:27+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/firmalex.com\/wp-content\/uploads\/2023\/07\/kapitalertragsteuer-in-spanien.jpg","type":"image\/jpeg"}],"author":"Firmalex","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Firmalex","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/#article","isPartOf":{"@id":"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/"},"author":{"name":"Firmalex","@id":"https:\/\/firmalex.com\/#\/schema\/person\/910549a246ed3ba83a193ed7ecbb51d2"},"headline":"Kapitalertragsteuer in Spanien","datePublished":"2023-06-09T08:35:00+00:00","dateModified":"2023-07-10T08:37:27+00:00","mainEntityOfPage":{"@id":"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/"},"wordCount":821,"publisher":{"@id":"https:\/\/firmalex.com\/#organization"},"image":{"@id":"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/#primaryimage"},"thumbnailUrl":"https:\/\/firmalex.com\/wp-content\/uploads\/2023\/07\/kapitalertragsteuer-in-spanien.jpg","articleSection":["Kauf und Verkauf von Immobilien","Neueste Artikel","Steuerberatung","Steuern in Spanien","Unternehmensberatung"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/","url":"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/","name":"Kapitalertragsteuer in Spanien - FIRMALEX","isPartOf":{"@id":"https:\/\/firmalex.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/#primaryimage"},"image":{"@id":"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/#primaryimage"},"thumbnailUrl":"https:\/\/firmalex.com\/wp-content\/uploads\/2023\/07\/kapitalertragsteuer-in-spanien.jpg","datePublished":"2023-06-09T08:35:00+00:00","dateModified":"2023-07-10T08:37:27+00:00","breadcrumb":{"@id":"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/#primaryimage","url":"https:\/\/firmalex.com\/wp-content\/uploads\/2023\/07\/kapitalertragsteuer-in-spanien.jpg","contentUrl":"https:\/\/firmalex.com\/wp-content\/uploads\/2023\/07\/kapitalertragsteuer-in-spanien.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/firmalex.com\/de\/2023\/06\/09\/kapitalertragsteuer-in-spanien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/firmalex.com\/de\/"},{"@type":"ListItem","position":2,"name":"Kapitalertragsteuer in Spanien"}]},{"@type":"WebSite","@id":"https:\/\/firmalex.com\/#website","url":"https:\/\/firmalex.com\/","name":"FIRMALEX","description":"Rechts-, Steuer-, Arbeits-, Buchhaltungs- und Unternehmensberatung in Denia (Alicante) und Valencia [Spanien]. Anwalt und Steuerberater.","publisher":{"@id":"https:\/\/firmalex.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/firmalex.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/firmalex.com\/#organization","name":"Firmalex","url":"https:\/\/firmalex.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/firmalex.com\/#\/schema\/logo\/image\/","url":"https:\/\/firmalex.com\/wp-content\/uploads\/2015\/02\/logo.jpg","contentUrl":"https:\/\/firmalex.com\/wp-content\/uploads\/2015\/02\/logo.jpg","width":371,"height":161,"caption":"Firmalex"},"image":{"@id":"https:\/\/firmalex.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/firmalex.com\/#\/schema\/person\/910549a246ed3ba83a193ed7ecbb51d2","name":"Firmalex","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/firmalex.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f6db6b06d3c80b6856de62666826e8b?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f6db6b06d3c80b6856de62666826e8b?s=96&d=blank&r=g","caption":"Firmalex"},"sameAs":["https:\/\/firmalex.com"]}]}},"_links":{"self":[{"href":"https:\/\/firmalex.com\/de\/wp-json\/wp\/v2\/posts\/12839"}],"collection":[{"href":"https:\/\/firmalex.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/firmalex.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/firmalex.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/firmalex.com\/de\/wp-json\/wp\/v2\/comments?post=12839"}],"version-history":[{"count":1,"href":"https:\/\/firmalex.com\/de\/wp-json\/wp\/v2\/posts\/12839\/revisions"}],"predecessor-version":[{"id":12843,"href":"https:\/\/firmalex.com\/de\/wp-json\/wp\/v2\/posts\/12839\/revisions\/12843"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/firmalex.com\/de\/wp-json\/wp\/v2\/media\/12840"}],"wp:attachment":[{"href":"https:\/\/firmalex.com\/de\/wp-json\/wp\/v2\/media?parent=12839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/firmalex.com\/de\/wp-json\/wp\/v2\/categories?post=12839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/firmalex.com\/de\/wp-json\/wp\/v2\/tags?post=12839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}